{"id":75096,"date":"2023-02-10T00:52:46","date_gmt":"2023-02-09T23:52:46","guid":{"rendered":"http:\/\/k-designfashion.com\/juridisch\/politique-en-matiere-de-cookies\/"},"modified":"2023-04-04T10:47:12","modified_gmt":"2023-04-04T08:47:12","slug":"politique-en-matiere-de-cookies","status":"publish","type":"page","link":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/","title":{"rendered":"Politique en mati\u00e8re de cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"75096\" class=\"elementor elementor-75096 elementor-38656\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f53c7b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f53c7b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ee7678\" data-id=\"6ee7678\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbd2801 elementor-widget elementor-widget-heading\" data-id=\"fbd2801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique en mati\u00e8re de cookies de K-Design Fashion<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc26a94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc26a94\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cbba60\" data-id=\"5cbba60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-921a7e0 elementor-widget elementor-widget-heading\" data-id=\"921a7e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 1. Pourquoi utilisons-nous des cookies ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f363b3f elementor-widget elementor-widget-text-editor\" data-id=\"f363b3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La pr\u00e9sente Politique en mati\u00e8re de cookies d\u00e9crit les cookies que nous utilisons sur le site web et \u00e0 quoi servent ces cookies. Nous utilisons des cookies pour les raisons suivantes :<\/p>\n<ul>\n<li>Pour garantir que le site web fonctionne correctement et vous offrir une exp\u00e9rience utilisateur optimale.<\/li>\n<li>Pour recenser le nombre de visiteurs qui se rendent sur notre site et les pages qu\u2019ils consultent.<\/li>\n<li>Pour permettre l\u2019int\u00e9gration des m\u00e9dias sociaux sur le site web.<\/li>\n<li>Pour g\u00e9n\u00e9rer des publicit\u00e9s adapt\u00e9es \u00e0 vos besoins.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73eda86 elementor-widget elementor-widget-heading\" data-id=\"73eda86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 2. Qu\u2019est-ce qu\u2019un cookie ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca4346d elementor-widget elementor-widget-text-editor\" data-id=\"ca4346d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un cookie est un simple petit fichier envoy\u00e9 avec les pages de ce site web et stock\u00e9 par le navigateur sur le disque dur de votre ordinateur. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs lors d\u2019une visite ult\u00e9rieure. Un cookie est un fichier contenant un identifiant (une s\u00e9rie de lettres et de chiffres) qui est envoy\u00e9 par un serveur web \u00e0 un navigateur web et stock\u00e9 par ce dernier. L\u2019identifiant est ensuite renvoy\u00e9 au serveur chaque fois que le navigateur demande une page du serveur. Les cookies sont de petits \u00e9l\u00e9ments de donn\u00e9es stock\u00e9s dans le navigateur d\u2019un visiteur. Ils sont g\u00e9n\u00e9ralement utilis\u00e9s pour garder une trace des param\u00e8tres que les utilisateurs ont s\u00e9lectionn\u00e9s et des actions qu\u2019ils ont effectu\u00e9es sur un site.<\/p>\n<p class=\"p1\">Les cookies ne peuvent pas \u00eatre utilis\u00e9s pour identifier des personnes ; un cookie ne peut identifier qu\u2019une machine. Les cookies ne contiennent g\u00e9n\u00e9ralement pas d\u2019informations permettant d\u2019identifier personnellement un utilisateur, mais les informations personnelles que nous stockons \u00e0 votre sujet peuvent \u00eatre li\u00e9es \u00e0 des informations stock\u00e9es dans les cookies et obtenues par les cookies.<span class=\"Apple-converted-space\"> <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff6980 elementor-widget elementor-widget-heading\" data-id=\"7ff6980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 3. Utilisation de cookies permanents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85f2977 elementor-widget elementor-widget-text-editor\" data-id=\"85f2977\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un cookie permanent nous permet de vous reconna\u00eetre lorsque vous visitez \u00e0 nouveau notre site web. Le site web peut d\u00e8s lors \u00eatre configur\u00e9 en fonction de vos pr\u00e9f\u00e9rences. Si vous avez donn\u00e9 votre consentement pour que des cookies soient plac\u00e9s, nous pouvons \u00e9galement nous en souvenir au moyen d\u2019un cookie. Cela vous \u00e9vite de devoir r\u00e9p\u00e9ter vos pr\u00e9f\u00e9rences \u00e0 chaque visite, ce qui vous fait gagner du temps et rend notre site web plus convivial. Vous pouvez supprimer les cookies permanents via les param\u00e8tres de votre navigateur.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81f7693 elementor-widget elementor-widget-heading\" data-id=\"81f7693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 4. Utilisation de cookies de session<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80f29fe elementor-widget elementor-widget-text-editor\" data-id=\"80f29fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un cookie de session nous permet de voir quelles parties du site web vous avez consult\u00e9es lors de cette visite. Cela nous permet d\u2019adapter au mieux notre service au comportement de navigation de nos visiteurs. Ces cookies sont automatiquement supprim\u00e9s d\u00e8s que vous fermez votre navigateur web.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d1e68 elementor-widget elementor-widget-heading\" data-id=\"e2d1e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 5. Google Analytics<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc595fc elementor-widget elementor-widget-text-editor\" data-id=\"cc595fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Par le biais de notre site web, un cookie est plac\u00e9 par la soci\u00e9t\u00e9 Google, dans le cadre du service \u00ab Analytics \u00bb. Nous utilisons ce service pour suivre et recevoir des rapports sur la fa\u00e7on dont les visiteurs utilisent le site web. Google peut communiquer ces informations \u00e0 des tiers si la loi l\u2019y oblige ou dans la mesure o\u00f9 des tiers traitent ces informations pour le compte de Google. Nous n\u2019avons aucune influence \u00e0 cet \u00e9gard. Nous n\u2019avons pas autoris\u00e9 Google \u00e0 utiliser les informations analytiques obtenues pour d\u2019autres services Google.<\/p>\n<p>Les informations collect\u00e9es par Google sont anonymis\u00e9es autant que possible. Votre adresse IP n\u2019est express\u00e9ment pas transmise. Les informations sont transf\u00e9r\u00e9es et stock\u00e9es par Google sur des serveurs situ\u00e9s aux \u00c9tats-Unis. Google d\u00e9clare respecter les principes relatifs au Bouclier de protection des donn\u00e9es (\u00ab Privacy Shield \u00bb) et \u00eatre affili\u00e9 au programme relatif au Bouclier de protection des donn\u00e9es du minist\u00e8re am\u00e9ricain du commerce. Cela implique un niveau de protection ad\u00e9quat pour le traitement de toute donn\u00e9e \u00e0 caract\u00e8re personnel.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea9a78 elementor-widget elementor-widget-heading\" data-id=\"0ea9a78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 6. Droit d\u2019acc\u00e8s et de rectification ou de suppression de vos donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d095440 elementor-widget elementor-widget-text-editor\" data-id=\"d095440\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous avez le droit de demander l\u2019acc\u00e8s \u00e0 vos donn\u00e9es ainsi que la rectification ou la suppression de celles-ci. Vous pouvez envoyer votre demande via le formulaire de contact en ligne. Pour \u00e9viter tout abus, nous pouvons vous demander de fournir une identification ad\u00e9quate \u00e0 cet \u00e9gard. Lorsqu\u2019il s\u2019agit d\u2019acc\u00e9der \u00e0 des donn\u00e9es \u00e0 caract\u00e8re personnel li\u00e9es \u00e0 un cookie, vous devez envoyer une copie du cookie en question. Vous pouvez le retrouver dans les param\u00e8tres de votre navigateur.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3539e35 elementor-widget elementor-widget-heading\" data-id=\"3539e35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 7. Activation, d\u00e9sactivation et suppression des cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af12c3 elementor-widget elementor-widget-text-editor\" data-id=\"1af12c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez configurer votre navigateur internet afin qu\u2019il n\u2019accepte pas les cookies, qu\u2019il vous avertisse lorsqu\u2019un cookie est install\u00e9 ou qu\u2019il supprime ensuite les cookies de votre disque dur. Vous trouverez de plus amples informations sur l\u2019activation, la d\u00e9sactivation et la suppression des cookies dans les instructions et\/ou en utilisant la fonction d\u2019aide de votre navigateur.<\/p>\n<p>La plupart des navigateurs vous permettent de refuser les cookies et de supprimer les cookies existants. Les m\u00e9thodes pour ce faire varient d\u2019un navigateur \u00e0 l\u2019autre et d\u2019une version \u00e0 l\u2019autre. Veuillez noter que certains \u00e9l\u00e9ments graphiques peuvent ne pas appara\u00eetre correctement ou que vous pouvez ne pas \u00eatre en mesure d\u2019utiliser certaines applications.<\/p>\n<p>Vous pouvez obtenir des informations actualis\u00e9es sur le blocage et la suppression des cookies via ces liens :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c7f514 elementor-widget elementor-widget-text-editor\" data-id=\"4c7f514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">\n<table class=\"t1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"td1\" valign=\"middle\">\n<p class=\"p3\">Navigateur<\/p>\n<\/td>\n<td class=\"td2\" valign=\"middle\">\n<p class=\"p3\">Lien<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td3\" valign=\"middle\">\n<p class=\"p4\">Chrome<\/p>\n<\/td>\n<td class=\"td4\" valign=\"middle\">\n<p class=\"p5\">https:\/\/support.google.com\/chrome\/answer\/95647?hl=nl<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td5\" valign=\"middle\">\n<p class=\"p4\">Firefox<\/p>\n<\/td>\n<td class=\"td6\" valign=\"middle\">\n<p class=\"p5\">https:\/\/support.mozilla.org\/en-US\/kb\/enable-and-disable-cookies-website-preferences<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td3\" valign=\"middle\">\n<p class=\"p4\">Opera<\/p>\n<\/td>\n<td class=\"td7\" valign=\"middle\">\n<p class=\"p5\">http:\/\/www.opera.com\/help\/tutorials\/security\/cookies<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td8\" valign=\"middle\">\n<p class=\"p4\">Internet Explorer<\/p>\n<\/td>\n<td class=\"td9\" valign=\"middle\">\n<p class=\"p5\">https:\/\/support.microsoft.com\/en-gb\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td5\" valign=\"middle\">\n<p class=\"p4\">Safari<\/p>\n<\/td>\n<td class=\"td10\" valign=\"middle\">\n<p class=\"p5\">https:\/\/support.apple.com\/kb\/PH21411<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td11\" valign=\"middle\">\n<p class=\"p4\">Edge<\/p>\n<\/td>\n<td class=\"td12\" valign=\"middle\">\n<p class=\"p5\">https:\/\/privacy.microsoft.com\/en-us\/windows-10-microsoft-edge-and-privacy<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"p6\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a1454 elementor-widget elementor-widget-heading\" data-id=\"29a1454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Article 8. Quel type de cookies nous utilisons<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20f00bb elementor-widget elementor-widget-text-editor\" data-id=\"20f00bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"t1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"td1\" valign=\"middle\">\n<p class=\"p1\">Type<\/p>\n<\/td>\n<td class=\"td2\" valign=\"middle\">\n<p class=\"p1\">Nom<\/p>\n<\/td>\n<td class=\"td1\" valign=\"middle\">\n<p class=\"p1\">Dur\u00e9e de vie<\/p>\n<\/td>\n<td class=\"td3\" valign=\"middle\">\n<p class=\"p1\">Finalit\u00e9<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td4\" valign=\"middle\">\n<p class=\"p2\">Cookie fonctionnel<\/p>\n<\/td>\n<td class=\"td5\" valign=\"middle\">\n<p class=\"p3\">Cookie-agreed<\/p>\n<\/td>\n<td class=\"td4\" valign=\"middle\">\n<p class=\"p3\">3 mois<\/p>\n<\/td>\n<td class=\"td6\" valign=\"middle\">\n<p class=\"p3\">Ce cookie est utilis\u00e9 pour suivre les pr\u00e9f\u00e9rences en mati\u00e8re d\u2019autorisations et de cookies.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td7\" valign=\"middle\">\n<p class=\"p2\">Cookie analytique<\/p>\n<\/td>\n<td class=\"td8\" valign=\"middle\">\n<p class=\"p3\">gat_gtag_UA_[number]<\/p>\n<\/td>\n<td class=\"td9\" valign=\"middle\">\n<p class=\"p3\">1 jour<\/p>\n<\/td>\n<td class=\"td10\" valign=\"middle\">\n<p class=\"p3\">Ce cookie est utilis\u00e9 pour affaiblir le nombre de demandes. Il s\u2019agit de cookies tiers qui sont plac\u00e9s sur votre appareil pour nous permettre d\u2019utiliser le service Google Analytics. Ces cookies sont utilis\u00e9s pour recueillir des informations sur la fa\u00e7on dont les visiteurs utilisent notre site web. Nous utilisons ces informations pour compiler des rapports et nous aider \u00e0 am\u00e9liorer le site web.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td11\" valign=\"middle\">\n<p class=\"p2\">Cookie analytique<\/p>\n<\/td>\n<td class=\"td12\" valign=\"middle\">\n<p class=\"p3\">_gid<\/p>\n<\/td>\n<td class=\"td11\" valign=\"middle\">\n<p class=\"p3\">1 jour<\/p>\n<\/td>\n<td class=\"td13\" valign=\"middle\">\n<p class=\"p3\">Ce cookie est install\u00e9 par Google Analytics. Le cookie est utilis\u00e9 pour stocker des informations sur la fa\u00e7on dont les visiteurs utilisent un site web et aide \u00e0 g\u00e9n\u00e9rer un<\/p>\n<p class=\"p3\">rapport d\u2019analyse sur la mani\u00e8re dont le site web fonctionne. Les donn\u00e9es collect\u00e9es comprennent le nombre de visiteurs, la source dont ils proviennent et les pages visit\u00e9es sous une forme anonyme.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"td4\" valign=\"middle\">\n<p class=\"p2\">Cookie analytique<\/p>\n<\/td>\n<td class=\"td14\" valign=\"middle\">\n<p class=\"p3\">_ga<\/p>\n<\/td>\n<td class=\"td15\" valign=\"middle\">\n<p class=\"p3\">2 ans<\/p>\n<\/td>\n<td class=\"td16\" valign=\"middle\">\n<p class=\"p3\">Ce cookie est un cookie permanent de Google Analytics qui est utilis\u00e9 pour distinguer les utilisateurs uniques.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"p5\">Vous avez des questions ou des commentaires sur notre Politique en mati\u00e8re de cookies ? Vous pouvez nous envoyer vos questions via le formulaire de contact en ligne.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique en mati\u00e8re de cookies de K-Design Fashion Article 1. Pourquoi utilisons-nous des cookies ? La pr\u00e9sente Politique en mati\u00e8re de cookies d\u00e9crit les cookies que nous utilisons sur le site web et \u00e0 quoi servent ces cookies. Nous utilisons des cookies pour les raisons suivantes : Pour garantir que le site web fonctionne correctement [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":74737,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-75096","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique en mati\u00e8re de cookies - K-Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique en mati\u00e8re de cookies - K-Design\" \/>\n<meta property=\"og:description\" content=\"Politique en mati\u00e8re de cookies de K-Design Fashion Article 1. Pourquoi utilisons-nous des cookies ? La pr\u00e9sente Politique en mati\u00e8re de cookies d\u00e9crit les cookies que nous utilisons sur le site web et \u00e0 quoi servent ces cookies. Nous utilisons des cookies pour les raisons suivantes : Pour garantir que le site web fonctionne correctement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"K-Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kdesignfashioncom\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T08:47:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/politique-en-matiere-de-cookies\\\/\",\"url\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/politique-en-matiere-de-cookies\\\/\",\"name\":\"Politique en mati\u00e8re de cookies - K-Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#website\"},\"datePublished\":\"2023-02-09T23:52:46+00:00\",\"dateModified\":\"2023-04-04T08:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/politique-en-matiere-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juridisch\",\"item\":\"https:\\\/\\\/k-designfashion.com\\\/fr\\\/juridisch\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Politique en mati\u00e8re de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#website\",\"url\":\"https:\\\/\\\/k-designfashion.com\\\/\",\"name\":\"K-Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-designfashion.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#organization\",\"name\":\"K-Design\",\"url\":\"https:\\\/\\\/k-designfashion.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-designfashion.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/k-Design_logo.png\",\"contentUrl\":\"https:\\\/\\\/k-designfashion.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/k-Design_logo.png\",\"width\":556,\"height\":394,\"caption\":\"K-Design\"},\"image\":{\"@id\":\"https:\\\/\\\/k-designfashion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kdesignfashioncom\\\/\",\"https:\\\/\\\/www.instagram.com\\\/kdesignfashion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique en mati\u00e8re de cookies - K-Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique en mati\u00e8re de cookies - K-Design","og_description":"Politique en mati\u00e8re de cookies de K-Design Fashion Article 1. Pourquoi utilisons-nous des cookies ? La pr\u00e9sente Politique en mati\u00e8re de cookies d\u00e9crit les cookies que nous utilisons sur le site web et \u00e0 quoi servent ces cookies. Nous utilisons des cookies pour les raisons suivantes : Pour garantir que le site web fonctionne correctement [&hellip;]","og_url":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/","og_site_name":"K-Design","article_publisher":"https:\/\/www.facebook.com\/kdesignfashioncom\/","article_modified_time":"2023-04-04T08:47:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/","url":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/","name":"Politique en mati\u00e8re de cookies - K-Design","isPartOf":{"@id":"https:\/\/k-designfashion.com\/#website"},"datePublished":"2023-02-09T23:52:46+00:00","dateModified":"2023-04-04T08:47:12+00:00","breadcrumb":{"@id":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-designfashion.com\/fr\/juridisch\/politique-en-matiere-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/k-designfashion.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Juridisch","item":"https:\/\/k-designfashion.com\/fr\/juridisch\/"},{"@type":"ListItem","position":3,"name":"Politique en mati\u00e8re de cookies"}]},{"@type":"WebSite","@id":"https:\/\/k-designfashion.com\/#website","url":"https:\/\/k-designfashion.com\/","name":"K-Design","description":"","publisher":{"@id":"https:\/\/k-designfashion.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-designfashion.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/k-designfashion.com\/#organization","name":"K-Design","url":"https:\/\/k-designfashion.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/k-designfashion.com\/#\/schema\/logo\/image\/","url":"https:\/\/k-designfashion.com\/wp-content\/uploads\/2022\/02\/k-Design_logo.png","contentUrl":"https:\/\/k-designfashion.com\/wp-content\/uploads\/2022\/02\/k-Design_logo.png","width":556,"height":394,"caption":"K-Design"},"image":{"@id":"https:\/\/k-designfashion.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kdesignfashioncom\/","https:\/\/www.instagram.com\/kdesignfashion\/"]}]}},"_links":{"self":[{"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/pages\/75096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/comments?post=75096"}],"version-history":[{"count":0,"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/pages\/75096\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/pages\/74737"}],"wp:attachment":[{"href":"https:\/\/k-designfashion.com\/fr\/wp-json\/wp\/v2\/media?parent=75096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}